{"id":13884,"date":"2023-04-02T20:16:51","date_gmt":"2023-04-02T17:16:51","guid":{"rendered":"https:\/\/lefrucom.com\/?page_id=13884"},"modified":"2023-06-07T14:14:04","modified_gmt":"2023-06-07T11:14:04","slug":"gutui-uscate-cuburi","status":"publish","type":"page","link":"https:\/\/lefrucom.com\/ru\/gutui-uscate-cuburi\/","title":{"rendered":"\u0410\u0439\u0432\u0430, \u0440\u0435\u0437\u0430\u043d\u0430\u044f \u043a\u0443\u0431\u0438\u043a\u043e\u043c, \u0441\u0443\u0448\u0435\u043d\u0430\u044f, \u043e\u0431\u0440\u0430\u0431\u043e\u0442\u0430\u043d\u043d\u0430\u044f"},"content":{"rendered":"<p>[vc_row][vc_column offset=&#187;vc_hidden-lg vc_hidden-md&#187; css=&#187;.vc_custom_1685731914096{padding-right: 8% !important;padding-left: 8% !important;}&#187;]<div class=\"eltdf-elements-holder eltdf-one-column eltdf-responsive-mode-768\" ><div class=\"eltdf-eh-item \"  data-item-class=\"eltdf-eh-custom-330801\">\n\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-330801\" >\n\t\t\t<div class=\"eltdf-section-title-holder eltdf-separator-disabled \" style=\"text-align: center\">\n\t\t\t<h3 class=\"eltdf-st-title eltdf-title-center\" style=\"color: #618a49\">\n\t\t\t<span>\u0410\u0419\u0412\u0410, \u0420\u0415\u0417\u0410\u041d\u0410\u042f \u041a\u0423\u0411\u0418\u041a\u041e\u041c, \u0421\u0423\u0428\u0415\u041d\u0410\u042f, \u041e\u0411\u0420\u0410\u0411\u041e\u0422\u0410\u041d\u041d\u0410\u042f<\/span>\n\t\t<\/h3>\n\t\t<\/div>[vc_empty_space height=&#187;50px&#187;]\t\t<\/div>\n\t<\/div>\n<\/div><\/div>[vc_column_text]<br \/>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#187;.vc_custom_1684664857254{margin-top: -50px !important;padding-top: 100px !important;}&#187; simple_background_color=&#187;#f9f9f9&#8243;][vc_column width=&#187;1\/2&#8243;][\/vc_column][vc_column width=&#187;1\/2&#8243; offset=&#187;vc_hidden-sm vc_hidden-xs&#187;]<div class=\"eltdf-elements-holder eltdf-one-column eltdf-responsive-mode-768\" ><div class=\"eltdf-eh-item \"  data-item-class=\"eltdf-eh-custom-194538\">\n\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-194538\" style=\"padding: 5% 20% 25px 5%\">\n\t\t\t<div class=\"eltdf-section-title-holder  \" >\n\t\t\t<h2 class=\"eltdf-st-title \" style=\"color: #618a49\">\n\t\t\t<span>\u0410\u0419\u0412\u0410, \u0420\u0415\u0417\u0410\u041d\u0410\u042f \u041a\u0423\u0411\u0418\u041a\u041e\u041c, \u0421\u0423\u0428\u0415\u041d\u0410\u042f, \u041e\u0411\u0420\u0410\u0411\u041e\u0422\u0410\u041d\u041d\u0410\u042f<\/span>\n\t\t<\/h2>\n\t\t\t\t<p class=\"eltdf-st-text\" style=\"font-size: 20px\">100g<\/p>\n\t<\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column][\/vc_row][vc_row css=&#187;.vc_custom_1685820357185{padding-bottom: 110px !important;}&#187;][vc_column offset=&#187;vc_hidden-sm vc_hidden-xs&#187;][vc_single_image image=&#187;14955&#8243; img_size=&#187;full&#187;][\/vc_column][\/vc_row][vc_row][vc_column width=&#187;1\/2&#8243; css=&#187;.vc_custom_1685868175763{margin-top: -45% !important;padding-right: 20% !important;padding-bottom: 120px !important;padding-left: 20% !important;}&#187;]<div class=\"eltdf-image-gallery eltdf-ig-carousel-type eltdf-image-behavior- \">\n\t<div class=\"eltdf-ig-slider eltdf-owl-slider\" data-number-of-items=\"1\" data-enable-loop=\"no\" data-enable-autoplay=\"no\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-enable-navigation=\"no\" data-enable-pagination=\"yes\">\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/GUTUI-USCATE_CUBURI.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/GUTUI-USCATE_CUBURI.png 600w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/GUTUI-USCATE_CUBURI-225x300.png 225w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>[\/vc_column][vc_column width=&#187;1\/2&#8243; css=&#187;.vc_custom_1685820337693{margin-top: -100px !important;margin-bottom: 50px !important;}&#187;]<div class=\"eltdf-elements-holder eltdf-one-column eltdf-responsive-mode-768\" ><div class=\"eltdf-eh-item \"  data-item-class=\"eltdf-eh-custom-535003\" data-1280-1600=\"0px 5% 0px 5%\" data-1024-1280=\"0px 5% 0px 5%\" data-768-1024=\"0px 5% 0px 5%\" data-600-768=\"0px 5% 0px 5%\" data-480-600=\"0px 5% 0px 5%\" data-480=\"0px 5% 0px 5%\">\n\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-535003\" style=\"padding: 0px 25% 0px 5%;\">\n\t\t\t[vc_column_text]C\u0443\u0448\u0435\u043d\u0430\u044f \u0430\u0439\u0432\u0430 \u0431\u0435\u0437 \u0434\u043e\u0431\u0430\u0432\u043b\u0435\u043d\u0438\u044f \u0441\u0430\u0445\u0430\u0440\u0430, \u0430\u0440\u043e\u043c\u0430\u0442\u0438\u0437\u0430\u0442\u043e\u0440\u043e\u0432 \u0438 \u0434\u0440\u0443\u0433\u0438\u0445 \u0434\u043e\u0431\u0430\u0432\u043e\u043a.<\/p>\n<p>\u0418\u0441\u043f\u043e\u043b\u044c\u0437\u0443\u044f \u043f\u043e\u043b\u043d\u043e\u0441\u0442\u044c\u044e \u043d\u0430\u0442\u0443\u0440\u0430\u043b\u044c\u043d\u044b\u0439 \u043f\u0440\u043e\u0446\u0435\u0441\u0441 \u0441\u0443\u0448\u043a\u0438, \u0442\u0435\u043f\u043b\u044b\u0439 \u0432\u043e\u0437\u0434\u0443\u0445 \u0447\u0430\u0441\u0430\u043c\u0438 \u043e\u0431\u0434\u0443\u0432\u0430\u0435\u0442 \u043b\u043e\u043c\u0442\u0438\u043a\u0438 \u0444\u0440\u0443\u043a\u0442\u043e\u0432, \u0447\u0442\u043e \u043f\u043e\u0437\u0432\u043e\u043b\u044f\u0435\u0442 \u0438\u043c \u0441\u043e\u0445\u0440\u0430\u043d\u044f\u0442\u044c \u0431\u043e\u043b\u044c\u0448\u0443\u044e \u0447\u0430\u0441\u0442\u044c \u0441\u0432\u043e\u0438\u0445 \u043f\u0438\u0442\u0430\u0442\u0435\u043b\u044c\u043d\u044b\u0445 \u0441\u0432\u043e\u0439\u0441\u0442\u0432 \u0438 \u0432\u043a\u0443\u0441\u0430 \u043d\u0430 \u043f\u0440\u043e\u0442\u044f\u0436\u0435\u043d\u0438\u0438 \u0434\u043b\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0433\u043e \u0432\u0440\u0435\u043c\u0435\u043d\u0438.<\/p>\n<p>C\u0443\u0448\u0435\u043d\u0430\u044f \u0430\u0439\u0432\u0430 \u0441\u043e\u0434\u0435\u0440\u0436\u0438\u0442 \u0431\u043e\u043b\u044c\u0448\u043e\u0435 \u043a\u043e\u043b\u0438\u0447\u0435\u0441\u0442\u0432\u043e \u0432\u0438\u0442\u0430\u043c\u0438\u043d\u043e\u0432 (\u0421, \u0410, \u0415 \u0438 \u0432\u0438\u0442\u0430\u043c\u0438\u043d\u044b \u0433\u0440\u0443\u043f\u043f\u044b \u0412) \u043c\u0438\u043a\u0440\u043e\u044d\u043b\u0435\u043c\u0435\u043d\u0442\u043e\u0432 \u0438 \u043c\u0438\u043d\u0435\u0440\u0430\u043b\u043e\u0432 (\u043c\u0435\u0434\u044c, \u043c\u0430\u0440\u0433\u0430\u043d\u0435\u0446, \u0436\u0435\u043b\u0435\u0437\u043e, \u0445\u0440\u043e\u043c, \u0439\u043e\u0434, \u043a\u0440\u0435\u043c\u043d\u0438\u0439, \u043a\u043e\u0431\u0430\u043b\u044c\u0442, \u043c\u043e\u043b\u0438\u0431\u0434\u0435\u043d, \u0444\u043e\u0441\u0444\u043e\u0440, \u043a\u0430\u043b\u044c\u0446\u0438\u0439, \u043a\u0430\u043b\u0438\u0439 \u0438 \u043c\u0430\u0433\u043d\u0438\u0439).<\/p>\n<p>C\u0443\u0448\u0435\u043d\u0430\u044f \u0430\u0439\u0432\u0430 \u0441\u043e\u0434\u0435\u0440\u0436\u0438\u0442 \u0431\u043e\u043b\u044c\u0448\u043e\u0435 \u043a\u043e\u043b\u0438\u0447\u0435\u0441\u0442\u0432\u043e \u0430\u043d\u0442\u0438\u043e\u043a\u0441\u0438\u0434\u0430\u043d\u0442\u043e\u0432. \u041e\u043d\u0430 \u0431\u043e\u0433\u0430\u0442\u0430 \u043f\u0435\u043a\u0442\u0438\u043d\u043e\u043c \u0438 \u043f\u0438\u0449\u0435\u0432\u044b\u043c\u0438 \u0432\u043e\u043b\u043e\u043a\u043d\u0430\u043c\u0438, \u0447\u0442\u043e \u043f\u043e\u0437\u0432\u043e\u043b\u044f\u0435\u0442 \u043d\u043e\u0440\u043c\u0430\u043b\u0438\u0437\u043e\u0432\u0430\u0442\u044c \u043f\u0438\u0449\u0435\u0432\u0430\u0440\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u0435 \u043f\u0440\u043e\u0446\u0435\u0441\u0441\u044b.[\/vc_column_text][vc_empty_space height=&#187;35px&#187;]\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"eltdf-elements-holder eltdf-one-column eltdf-responsive-mode-768 eltdf-one-column-alignment-center\" ><div class=\"eltdf-eh-item \"  data-item-class=\"eltdf-eh-custom-434044\" data-1280-1600=\"0px 5% 0px 5%\" data-1024-1280=\"0px 5% 0px 5%\" data-768-1024=\"0px 5% 0px 5%\" data-600-768=\"0px 5% 0px 5%\" data-480-600=\"0px 5% 0px 5%\" data-480=\"0px 5% 0px 5%\">\n\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-434044\" style=\"padding: 0px 25% 0px 5%;\">\n\t\t\t<a itemprop=\"url\" href=\"https:\/\/lefrucom.com\/ru\/shop\/dried-fruits\/gutui-uscate-cuburi\/\" target=\"_self\"  class=\"eltdf-btn eltdf-btn-medium eltdf-btn-solid\"  >\n    <span class=\"eltdf-btn-text\">\u041a\u0443\u043f\u0438\u0442\u044c<\/span>\n    <\/a>\t\t<\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column][\/vc_row][vc_row row_content_width=&#187;grid&#187; css=&#187;.vc_custom_1684663143433{padding-top: 50px !important;padding-bottom: 50px !important;}&#187; simple_background_color=&#187;#ffffff&#187;][vc_column][vc_column_text]<br \/>\n<strong>\u0421\u041e\u0421\u0422\u0410\u0412: <\/strong>\u0430\u0439\u0432\u0430, \u0440\u0435\u0437\u0430\u043d\u043d\u0430\u044f \u043a\u0443\u0431\u0438\u043a\u043e\u043c, \u0441\u0443\u0448\u0435\u043d\u043d\u0430\u044f, (\u0430\u043d\u0442\u0438\u043e\u043a\u0441\u0438\u0434\u0430\u043d\u0442: \u041f\u0438\u0440\u043e\u0441\u0443\u043b\u044c\u0444\u0438\u0442 \u043d\u0430\u0442\u0440\u0438\u044f(\u0415223)<\/p>\n<p><strong>\u0423\u0421\u041b\u041e\u0412\u0418\u042f \u0425\u0420\u0410\u041d\u0415\u041d\u0418\u042f: <\/strong>\u043f\u0440\u0438 \u0442\u0435\u043c\u043f\u0435\u0440\u0430\u0442\u0443\u0440\u0435 \u043e\u0442 5 \u0434\u043e 20\u00b0C<\/p>\n<p><strong>\u041e\u0422\u041d\u041e\u0421\u0418\u0422\u0415\u041b\u042c\u041d\u0410\u042f \u0412\u041b\u0410\u0416\u041d\u041e\u0421\u0422\u042c: <\/strong>\u043c\u0430\u043a\u0441. 70%<\/p>\n<p><strong>\u0423\u041f\u041e\u0422\u0420\u0415\u0411\u0418\u0422\u042c \u0414\u041e: <\/strong>\u0441\u043c\u043e\u0442\u0440\u0435\u0442\u044c \u043d\u0430 \u0443\u043f\u0430\u043a\u043e\u0432\u043a\u0435<\/p>\n<p><strong>\u0421\u0420\u041e\u041a \u0413\u041e\u0414\u041d\u041e\u0421\u0422\u0418: <\/strong>12 \u043c\u0435\u0441\u044f\u0446\u0435\u0432<\/p>\n<p><strong><span style=\"color: #ff0000;\">!\u0412\u041d\u0418\u041c\u0410\u041d\u0418\u0415:<\/span> \u041d\u0435\u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u043a\u0443\u0441\u043e\u0447\u043a\u0438 \u043f\u043b\u043e\u0434\u0430 \u043c\u043e\u0433\u0443\u0442 \u0441\u043e\u0434\u0435\u0440\u0436\u0430\u0442\u044c \u043e\u0442\u0434\u0435\u043b\u044c\u043d\u044b\u0435 \u0441\u0435\u043c\u0435\u043d\u0430 \u0438\u043b\u0438 \u0444\u0440\u0430\u0433\u043c\u0435\u043d\u0442\u044b \u0441\u0435\u043c\u044f\u043d.<\/strong><\/p>\n<p><strong>Package<\/strong><strong> (100 gr): EAN &#8212; 4841434000688 Price: 20 MDL<\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_content_width=&#187;grid&#187; simple_background_color=&#187;#fafafa&#187; css=&#187;.vc_custom_1680634681606{padding-top: 50px !important;padding-bottom: 50px !important;}&#187;][vc_column]<div class=\"eltdf-section-title-holder  \" style=\"text-align: center\">\n\t\t\t<h2 class=\"eltdf-st-title eltdf-title-center\" style=\"color: #618a49\">\n\t\t\t<span>\u0413\u0430\u043b\u0435\u0440\u0435\u044f<\/span>\n\t\t<\/h2>\n\t\t<\/div><div class=\"eltdf-image-gallery eltdf-ig-carousel-type eltdf-image-behavior-lightbox \">\n\t<div class=\"eltdf-ig-slider eltdf-owl-slider\" data-number-of-items=\"3\" data-enable-loop=\"yes\" data-enable-autoplay=\"yes\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-enable-navigation=\"yes\" data-enable-pagination=\"yes\">\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"eltdf-ig-lightbox\" href=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_0b.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-688]\" title=\"26.-GUTUI_USCATE_CUBURI_0b\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_0b.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_0b.jpg 1000w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_0b-300x300.jpg 300w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_0b-150x150.jpg 150w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_0b-768x768.jpg 768w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_0b-550x550.jpg 550w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_0b-600x600.jpg 600w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_0b-100x100.jpg 100w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_0b-375x375.jpg 375w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"eltdf-ig-lightbox\" href=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_1.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-688]\" title=\"26.-GUTUI_USCATE_CUBURI_1\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_1.jpg 1000w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_1-300x300.jpg 300w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_1-150x150.jpg 150w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_1-768x768.jpg 768w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_1-550x550.jpg 550w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_1-600x600.jpg 600w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_1-100x100.jpg 100w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_1-375x375.jpg 375w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"eltdf-ig-lightbox\" href=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_2.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-688]\" title=\"26.-GUTUI_USCATE_CUBURI_2\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_2.jpg 1000w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_2-300x300.jpg 300w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_2-150x150.jpg 150w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_2-768x768.jpg 768w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_2-550x550.jpg 550w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_2-600x600.jpg 600w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_2-100x100.jpg 100w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_2-375x375.jpg 375w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"eltdf-ig-lightbox\" href=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_3.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-688]\" title=\"26.-GUTUI_USCATE_CUBURI_3\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_3.jpg 1000w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_3-300x300.jpg 300w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_3-150x150.jpg 150w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_3-768x768.jpg 768w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_3-550x550.jpg 550w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_3-600x600.jpg 600w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_3-100x100.jpg 100w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/26.-GUTUI_USCATE_CUBURI_3-375x375.jpg 375w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"eltdf-ig-lightbox\" href=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/GUTUI_USCATE_CUBURI800x800.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-688]\" title=\"GUTUI_USCATE_CUBURI800x800\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/GUTUI_USCATE_CUBURI800x800.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/GUTUI_USCATE_CUBURI800x800.jpg 1000w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/GUTUI_USCATE_CUBURI800x800-300x300.jpg 300w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/GUTUI_USCATE_CUBURI800x800-150x150.jpg 150w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/GUTUI_USCATE_CUBURI800x800-768x768.jpg 768w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/GUTUI_USCATE_CUBURI800x800-550x550.jpg 550w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/GUTUI_USCATE_CUBURI800x800-600x600.jpg 600w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/GUTUI_USCATE_CUBURI800x800-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column offset=&#187;vc_hidden-lg vc_hidden-md&#187; css=&#187;.vc_custom_1685731914096{padding-right: 8% !important;padding-left: 8% !important;}&#187;][vc_column_text] [\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#187;.vc_custom_1684664857254{margin-top: -50px !important;padding-top: 100px !important;}&#187; simple_background_color=&#187;#f9f9f9&#8243;][vc_column width=&#187;1\/2&#8243;][\/vc_column][vc_column width=&#187;1\/2&#8243; offset=&#187;vc_hidden-sm vc_hidden-xs&#187;][\/vc_column][\/vc_row][vc_row css=&#187;.vc_custom_1685820357185{padding-bottom: 110px !important;}&#187;][vc_column offset=&#187;vc_hidden-sm vc_hidden-xs&#187;][vc_single_image image=&#187;14955&#8243; img_size=&#187;full&#187;][\/vc_column][\/vc_row][vc_row][vc_column width=&#187;1\/2&#8243; css=&#187;.vc_custom_1685868175763{margin-top: -45% !important;padding-right: 20% !important;padding-bottom: 120px !important;padding-left: 20% !important;}&#187;][\/vc_column][vc_column width=&#187;1\/2&#8243; css=&#187;.vc_custom_1685820337693{margin-top: -100px !important;margin-bottom: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-13884","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lefrucom.com\/ru\/wp-json\/wp\/v2\/pages\/13884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lefrucom.com\/ru\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lefrucom.com\/ru\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lefrucom.com\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lefrucom.com\/ru\/wp-json\/wp\/v2\/comments?post=13884"}],"version-history":[{"count":16,"href":"https:\/\/lefrucom.com\/ru\/wp-json\/wp\/v2\/pages\/13884\/revisions"}],"predecessor-version":[{"id":15288,"href":"https:\/\/lefrucom.com\/ru\/wp-json\/wp\/v2\/pages\/13884\/revisions\/15288"}],"wp:attachment":[{"href":"https:\/\/lefrucom.com\/ru\/wp-json\/wp\/v2\/media?parent=13884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}