{"id":14598,"date":"2023-05-15T12:01:20","date_gmt":"2023-05-15T09:01:20","guid":{"rendered":"https:\/\/lefrucom.com\/?page_id=14598"},"modified":"2023-06-04T14:52:13","modified_gmt":"2023-06-04T11:52:13","slug":"visine-in-ciocolata-neagra","status":"publish","type":"page","link":"https:\/\/lefrucom.com\/ro\/visine-in-ciocolata-neagra\/","title":{"rendered":"Vi\u0219ine \u00een ciocolat\u0103 neagr\u0103"},"content":{"rendered":"<p>[vc_row][vc_column offset=&#8221;vc_hidden-lg vc_hidden-md&#8221; css=&#8221;.vc_custom_1685731914096{padding-right: 8% !important;padding-left: 8% !important;}&#8221;]<div class=\"eltdf-elements-holder eltdf-one-column eltdf-responsive-mode-768\" ><div class=\"eltdf-eh-item \"  data-item-class=\"eltdf-eh-custom-974017\">\n\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-974017\" >\n\t\t\t<div class=\"eltdf-section-title-holder eltdf-separator-disabled \" style=\"text-align: center\">\n\t\t\t<h3 class=\"eltdf-st-title eltdf-title-center\" style=\"color: #618a49\">\n\t\t\t<span>DRAJEURI CU VI\u0218INE USCATE \u00ceN GLAZUR\u0102 DE COFET\u0102RIE NEAGR\u0102<\/span>\n\t\t<\/h3>\n\t\t<\/div>[vc_empty_space height=&#8221;50px&#8221;]\t\t<\/div>\n\t<\/div>\n<\/div><\/div>[vc_column_text]<br \/>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1684664857254{margin-top: -50px !important;padding-top: 100px !important;}&#8221; simple_background_color=&#8221;#f9f9f9&#8243;][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;]<div class=\"eltdf-elements-holder eltdf-one-column eltdf-responsive-mode-768\" ><div class=\"eltdf-eh-item \"  data-item-class=\"eltdf-eh-custom-794116\">\n\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-794116\" style=\"padding: 5% 20% 25px 5%\">\n\t\t\t<div class=\"eltdf-section-title-holder  \" >\n\t\t\t<h2 class=\"eltdf-st-title \" style=\"color: #618a49\">\n\t\t\t<span>DRAJEURI CU VI\u0218INE USCATE \u00ceN GLAZUR\u0102 DE COFET\u0102RIE NEAGR\u0102<\/span>\n\t\t<\/h2>\n\t\t\t\t<p class=\"eltdf-st-text\" style=\"font-size: 20px\">100g | 200g<\/p>\n\t<\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][vc_single_image image=&#8221;14816&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row][vc_row gap=&#8221;5&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1685871311417{margin-top: -30% !important;margin-bottom: 50px !important;padding-right: 20% !important;padding-left: 20% !important;}&#8221; offset=&#8221;vc_col-xs-12&#8243;]<div class=\"eltdf-image-gallery eltdf-ig-slider-type eltdf-image-behavior- \">\n\t<div class=\"eltdf-ig-slider eltdf-owl-slider\" data-number-of-items=\"1\" data-enable-loop=\"no\" data-enable-autoplay=\"no\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-enable-navigation=\"yes\" data-enable-pagination=\"yes\">\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/Visine-in-ciocolata-neagra-1-600x800.png\" alt=\"\" width=\"600\" height=\"800\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/Visine-in-ciocolata-neagra-2-600x800.png\" alt=\"\" width=\"600\" height=\"800\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space]<div class=\"eltdf-elements-holder eltdf-one-column eltdf-responsive-mode-768\" ><div class=\"eltdf-eh-item \"  data-item-class=\"eltdf-eh-custom-717126\" data-1024-1280=\"0px 3% 0px 0%\">\n\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-717126\" style=\"padding: 0px 5% 25px 5%\">\n\t\t\t[vc_column_text]Vi\u0219inele uscate sunt o gustare delicioas\u0103 \u00eentre mese, dar c\u00e2nd acestea sunt acoperite cu ciocolat\u0103 neagr\u0103, distrac\u021bia gastronomic\u0103 abia \u00eencepe. Caracterul dulce fructat \u0219i suculent al vi\u0219inei rezult\u0103 \u00eentr-o explozie de gust de neegalat, \u00eenso\u021bit\u0103 de aroma ciocolatei crocante.[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221;]\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"eltdf-elements-holder eltdf-one-column eltdf-responsive-mode-1280 eltdf-one-column-alignment-center\" ><div class=\"eltdf-eh-item \"  data-item-class=\"eltdf-eh-custom-464446\" data-1024-1280=\"0px 3% 0px 0%\">\n\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-464446\" style=\"padding: 0px 5% 25px 5%\">\n\t\t\t<a itemprop=\"url\" href=\"https:\/\/lefrucom.com\/ro\/shop\/dragee\/visine-in-ciocolata-neagra\/\" target=\"_self\"  class=\"eltdf-btn eltdf-btn-medium eltdf-btn-solid\"  >\n    <span class=\"eltdf-btn-text\">Cumpara Acum<\/span>\n    <\/a>\t\t<\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column][\/vc_row][vc_row row_content_width=&#8221;grid&#8221; css=&#8221;.vc_custom_1684663143433{padding-top: 50px !important;padding-bottom: 50px !important;}&#8221; simple_background_color=&#8221;#ffffff&#8221;][vc_column][vc_column_text]<strong>DRAJEURI CU VI\u0218INE USCATE \u00ceN GLAZUR\u0102 DE COFET\u0102RIE NEAGR\u0102<\/strong><\/p>\n<p><strong>INGREDIENTE:<\/strong> vi\u0219ine uscate f\u0103r\u0103 s\u00e2mburi, glazur\u0103 de cofet\u0103rie neagr\u0103 (zah\u0103r, gr\u0103simi vegetale rafinate \u0219i total hidrogenate (din s\u00e2mburi de palmier), pudr\u0103 de cacao cu con\u021binut redus de gr\u0103sime, emulgator: lecitin\u0103 de soia (E322), aromatizator identic natural: vanilin\u0103).<\/p>\n<p><strong>CONDI\u021aII DE P\u0102STRARE:<\/strong> la temperatura de la 15..21\u00b0C<\/p>\n<p><strong>UMIDITATE RELATIV\u0102:<\/strong> 75% max.<\/p>\n<p><strong>A SE CONSUMA P\u00c2N\u0102 L<\/strong>A: vezi pe ambalaj.<\/p>\n<p><strong>TERMEN DE VALABILITATE:<\/strong> 6 luni.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>!ATEN\u021aIE: <\/strong><\/span><strong>Corpurile de fructe pot con\u021bine izolat s\u00e2mburi sau fragmente de s\u00e2mburi.<\/strong><\/p>\n<p><strong>Triunghi mare\u00a0 \u00a0 (200 gr): EAN &#8211; 4841434000541\u00a0 \u00a0 Pre\u021b: 65.00 MDL<\/strong><br \/>\n<strong>Dreptunghi mic (100 gr): EAN &#8211; 4841434000848\u00a0 \u00a0 Pre\u021b: 35.00 MDL<\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_content_width=&#8221;grid&#8221; simple_background_color=&#8221;#fafafa&#8221; css=&#8221;.vc_custom_1680634681606{padding-top: 50px !important;padding-bottom: 50px !important;}&#8221;][vc_column]<div class=\"eltdf-section-title-holder  \" style=\"text-align: center\">\n\t\t\t<h2 class=\"eltdf-st-title eltdf-title-center\" style=\"color: #618a49\">\n\t\t\t<span>Galerie<\/span>\n\t\t<\/h2>\n\t\t<\/div><div class=\"eltdf-image-gallery eltdf-ig-carousel-type eltdf-image-behavior-lightbox \">\n\t<div class=\"eltdf-ig-slider eltdf-owl-slider\" data-number-of-items=\"3\" data-enable-loop=\"yes\" data-enable-autoplay=\"yes\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-enable-navigation=\"yes\" data-enable-pagination=\"yes\">\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"eltdf-ig-lightbox\" href=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/05\/VISINA_IN_CIOCOLATA_NEAGRA.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-760]\" title=\"VISINA_IN_CIOCOLATA_NEAGRA\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/05\/VISINA_IN_CIOCOLATA_NEAGRA.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/05\/VISINA_IN_CIOCOLATA_NEAGRA.jpg 1000w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/05\/VISINA_IN_CIOCOLATA_NEAGRA-300x300.jpg 300w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/05\/VISINA_IN_CIOCOLATA_NEAGRA-150x150.jpg 150w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/05\/VISINA_IN_CIOCOLATA_NEAGRA-768x768.jpg 768w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/05\/VISINA_IN_CIOCOLATA_NEAGRA-550x550.jpg 550w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/05\/VISINA_IN_CIOCOLATA_NEAGRA-600x600.jpg 600w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/05\/VISINA_IN_CIOCOLATA_NEAGRA-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"eltdf-ig-lightbox\" href=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_2.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-760]\" title=\"8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_2\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_2.jpg 1000w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_2-300x300.jpg 300w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_2-150x150.jpg 150w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_2-768x768.jpg 768w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_2-550x550.jpg 550w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_2-600x600.jpg 600w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_2-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"eltdf-ig-lightbox\" href=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_2.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-760]\" title=\"7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_2\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_2.jpg 1000w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_2-300x300.jpg 300w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_2-150x150.jpg 150w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_2-768x768.jpg 768w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_2-550x550.jpg 550w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_2-600x600.jpg 600w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_2-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"eltdf-ig-lightbox\" href=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_0.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-760]\" title=\"7.-VISINA_IN_CIOCOLATA_NEAGRA_0\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_0.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_0.jpg 1000w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_0-300x300.jpg 300w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_0-150x150.jpg 150w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_0-768x768.jpg 768w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_0-550x550.jpg 550w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_0-600x600.jpg 600w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_0-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"eltdf-ig-lightbox\" href=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_1.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-760]\" title=\"7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_1\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_1.jpg 1000w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_1-300x300.jpg 300w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_1-150x150.jpg 150w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_1-768x768.jpg 768w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_1-550x550.jpg 550w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_1-600x600.jpg 600w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/7.-VISINA_IN_CIOCOLATA_NEAGRA_DREPTUNGHI_MIC_1-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"eltdf-ig-lightbox\" href=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/05\/8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_1b.png\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-760]\" title=\"8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_1b\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/05\/8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_1b.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/05\/8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_1b.png 1000w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/05\/8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_1b-300x300.png 300w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/05\/8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_1b-150x150.png 150w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/05\/8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_1b-768x768.png 768w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/05\/8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_1b-550x550.png 550w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/05\/8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_1b-600x600.png 600w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/05\/8.-VISINA_IN_CIOCOLATA_NEAGRA_TRIUNGHI_MARE_1b-100x100.png 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column offset=&#8221;vc_hidden-lg vc_hidden-md&#8221; css=&#8221;.vc_custom_1685731914096{padding-right: 8% !important;padding-left: 8% !important;}&#8221;][vc_column_text] [\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1684664857254{margin-top: -50px !important;padding-top: 100px !important;}&#8221; simple_background_color=&#8221;#f9f9f9&#8243;][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column][\/vc_row][vc_row][vc_column offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][vc_single_image image=&#8221;14816&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row][vc_row gap=&#8221;5&#8243;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1685871311417{margin-top: -30% !important;margin-bottom: 50px !important;padding-right: 20% !important;padding-left: 20% !important;}&#8221; offset=&#8221;vc_col-xs-12&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space][\/vc_column][\/vc_row][vc_row row_content_width=&#8221;grid&#8221; css=&#8221;.vc_custom_1684663143433{padding-top: 50px !important;padding-bottom: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-14598","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lefrucom.com\/ro\/wp-json\/wp\/v2\/pages\/14598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lefrucom.com\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lefrucom.com\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lefrucom.com\/ro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lefrucom.com\/ro\/wp-json\/wp\/v2\/comments?post=14598"}],"version-history":[{"count":176,"href":"https:\/\/lefrucom.com\/ro\/wp-json\/wp\/v2\/pages\/14598\/revisions"}],"predecessor-version":[{"id":15108,"href":"https:\/\/lefrucom.com\/ro\/wp-json\/wp\/v2\/pages\/14598\/revisions\/15108"}],"wp:attachment":[{"href":"https:\/\/lefrucom.com\/ro\/wp-json\/wp\/v2\/media?parent=14598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}