{"id":13828,"date":"2023-04-02T19:57:35","date_gmt":"2023-04-02T16:57:35","guid":{"rendered":"https:\/\/lefrucom.com\/?page_id=13828"},"modified":"2023-06-04T21:56:26","modified_gmt":"2023-06-04T18:56:26","slug":"mere-uscate-rondele-fara-coaja","status":"publish","type":"page","link":"https:\/\/lefrucom.com\/ro\/mere-uscate-rondele-fara-coaja\/","title":{"rendered":"Mere uscate rondele f\u0103r\u0103 coaj\u0103"},"content":{"rendered":"<p>[vc_row][vc_column offset=&#8221;vc_hidden-lg vc_hidden-md&#8221; css=&#8221;.vc_custom_1685731914096{padding-right: 8% !important;padding-left: 8% !important;}&#8221;]<div class=\"eltdf-elements-holder eltdf-one-column eltdf-responsive-mode-768\" ><div class=\"eltdf-eh-item \"  data-item-class=\"eltdf-eh-custom-859916\">\n\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-859916\" >\n\t\t\t<div class=\"eltdf-section-title-holder eltdf-separator-disabled \" style=\"text-align: center\">\n\t\t\t<h3 class=\"eltdf-st-title eltdf-title-center\" style=\"color: #618a49\">\n\t\t\t<span>MERE USCATE RONDELE F\u0102R\u0102 COAJ\u0102, PRELUCRATE<\/span>\n\t\t<\/h3>\n\t\t<\/div>[vc_empty_space height=&#8221;50px&#8221;]\t\t<\/div>\n\t<\/div>\n<\/div><\/div>[vc_column_text]<br \/>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1684664857254{margin-top: -50px !important;padding-top: 100px !important;}&#8221; simple_background_color=&#8221;#f9f9f9&#8243;][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;]<div class=\"eltdf-elements-holder eltdf-one-column eltdf-responsive-mode-768\" ><div class=\"eltdf-eh-item \"  data-item-class=\"eltdf-eh-custom-673946\">\n\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-673946\" style=\"padding: 5% 20% 25px 5%\">\n\t\t\t<div class=\"eltdf-section-title-holder  \" >\n\t\t\t<h2 class=\"eltdf-st-title \" style=\"color: #618a49\">\n\t\t\t<span>MERE USCATE RONDELE F\u0102R\u0102 COAJ\u0102, PRELUCRATE<\/span>\n\t\t<\/h2>\n\t\t\t\t<p class=\"eltdf-st-text\" style=\"font-size: 20px\">50g<\/p>\n\t<\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1685820357185{padding-bottom: 110px !important;}&#8221;][vc_column offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][vc_single_image image=&#8221;14955&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1685868175763{margin-top: -45% !important;padding-right: 20% !important;padding-bottom: 120px !important;padding-left: 20% !important;}&#8221;]<div class=\"eltdf-image-gallery eltdf-ig-carousel-type eltdf-image-behavior- \">\n\t<div class=\"eltdf-ig-slider eltdf-owl-slider\" data-number-of-items=\"1\" data-enable-loop=\"no\" data-enable-autoplay=\"no\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-enable-navigation=\"no\" data-enable-pagination=\"yes\">\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/MERE_USCATE_RONDELE_FARA_COA.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/MERE_USCATE_RONDELE_FARA_COA.png 600w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/MERE_USCATE_RONDELE_FARA_COA-225x300.png 225w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1685820337693{margin-top: -100px !important;margin-bottom: 50px !important;}&#8221;]<div class=\"eltdf-elements-holder eltdf-one-column eltdf-responsive-mode-768\" ><div class=\"eltdf-eh-item \"  data-item-class=\"eltdf-eh-custom-770065\" data-1280-1600=\"0px 5% 0px 5%\" data-1024-1280=\"0px 5% 0px 5%\" data-768-1024=\"0px 5% 0px 5%\" data-600-768=\"0px 5% 0px 5%\" data-480-600=\"0px 5% 0px 5%\" data-480=\"0px 5% 0px 5%\">\n\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-770065\" style=\"padding: 0px 25% 0px 5%;\">\n\t\t\t[vc_column_text]\u041c\u0435\u0433\u0435 deshidratate f\u0103r\u0103 adaos de zah\u0103r, arome sau al\u021bi aditivi. Folosind un proces de uscare complet natural, aerul cald este suflat peste feliile de fructe ore \u0219i ore p\u00e2n\u0103 c\u00e2nd devin crocante \u0219i delicioase.[\/vc_column_text][vc_empty_space height=&#8221;35px&#8221;]\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"eltdf-elements-holder eltdf-one-column eltdf-responsive-mode-768 eltdf-one-column-alignment-center\" ><div class=\"eltdf-eh-item \"  data-item-class=\"eltdf-eh-custom-392970\" data-1280-1600=\"0px 5% 0px 5%\" data-1024-1280=\"0px 5% 0px 5%\" data-768-1024=\"0px 5% 0px 5%\" data-600-768=\"0px 5% 0px 5%\" data-480-600=\"0px 5% 0px 5%\" data-480=\"0px 5% 0px 5%\">\n\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-392970\" style=\"padding: 0px 25% 0px 5%;\">\n\t\t\t<a itemprop=\"url\" href=\"https:\/\/lefrucom.com\/ro\/shop\/dried-fruits\/mere-uscate-rondele-fara-coaja\/\" target=\"_self\"  class=\"eltdf-btn eltdf-btn-medium eltdf-btn-solid\"  >\n    <span class=\"eltdf-btn-text\">Cumpara acum<\/span>\n    <\/a>\t\t<\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column][\/vc_row][vc_row row_content_width=&#8221;grid&#8221; css=&#8221;.vc_custom_1684663143433{padding-top: 50px !important;padding-bottom: 50px !important;}&#8221; simple_background_color=&#8221;#ffffff&#8221;][vc_column][vc_column_text]<strong>INGREDIENTE:<\/strong> mere uscate rondele, antioxidant: metabisulfite de sodiu (E223).<\/p>\n<p><strong>CONDI\u021aII DE P\u0102STRARE:<\/strong> la temperatura de la 5 la 20\u00b0C<\/p>\n<p><strong>UMIDITATE RELATIV\u0102:<\/strong> 70% max<\/p>\n<p><strong>A SE CONSUM\u0102 P\u00c2N\u0102 LA: <\/strong>vezi pe ambalaj<\/p>\n<p><strong>TERMEN DE VALABILITATE:<\/strong> 12 luni<\/p>\n<p><span style=\"color: #ff0000;\"><strong>!ATEN\u021aIE: <\/strong><\/span><strong>Corpurile de fructe pot con\u021bine izolat s\u00e2mburi sau fragmente de s\u00e2mburi.<\/strong><\/p>\n<p><strong>Triunghi mic (50 gr):\u00a0 EAN &#8211; 4841434000794 Pre\u021b: 20 MDL<\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_content_width=&#8221;grid&#8221; simple_background_color=&#8221;#fafafa&#8221; css=&#8221;.vc_custom_1680634681606{padding-top: 50px !important;padding-bottom: 50px !important;}&#8221;][vc_column]<div class=\"eltdf-section-title-holder  \" style=\"text-align: center\">\n\t\t\t<h2 class=\"eltdf-st-title eltdf-title-center\" style=\"color: #618a49\">\n\t\t\t<span>Galerie<\/span>\n\t\t<\/h2>\n\t\t<\/div><div class=\"eltdf-image-gallery eltdf-ig-carousel-type eltdf-image-behavior-lightbox \">\n\t<div class=\"eltdf-ig-slider eltdf-owl-slider\" data-number-of-items=\"3\" data-enable-loop=\"yes\" data-enable-autoplay=\"yes\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-enable-navigation=\"yes\" data-enable-pagination=\"yes\">\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"eltdf-ig-lightbox\" href=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_0.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-922]\" title=\"21.-MERE_USCATE_RONDELE_F\u0102R\u0102_COAJ\u0102_0\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_0.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_0.jpg 1000w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_0-300x300.jpg 300w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_0-150x150.jpg 150w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_0-768x768.jpg 768w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_0-550x550.jpg 550w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_0-600x600.jpg 600w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_0-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"eltdf-ig-lightbox\" href=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_1.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-922]\" title=\"21.-MERE_USCATE_RONDELE_F\u0102R\u0102_COAJ\u0102_1\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_1.jpg 1000w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_1-300x300.jpg 300w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_1-150x150.jpg 150w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_1-768x768.jpg 768w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_1-550x550.jpg 550w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_1-600x600.jpg 600w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_1-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"eltdf-ig-lightbox\" href=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/MERE_USCATE_RONDELE_FARA_COAJA.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-922]\" title=\"MERE_USCATE_RONDELE_F\u0102R\u0102_COAJ\u0102\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/MERE_USCATE_RONDELE_FARA_COAJA.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/MERE_USCATE_RONDELE_FARA_COAJA.jpg 800w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/MERE_USCATE_RONDELE_FARA_COAJA-300x300.jpg 300w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/MERE_USCATE_RONDELE_FARA_COAJA-150x150.jpg 150w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/MERE_USCATE_RONDELE_FARA_COAJA-768x768.jpg 768w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/MERE_USCATE_RONDELE_FARA_COAJA-550x550.jpg 550w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/MERE_USCATE_RONDELE_FARA_COAJA-600x600.jpg 600w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/MERE_USCATE_RONDELE_FARA_COAJA-100x100.jpg 100w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/03\/MERE_USCATE_RONDELE_FARA_COAJA-375x375.jpg 375w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"eltdf-ig-lightbox\" href=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_2.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-922]\" title=\"21.-MERE_USCATE_RONDELE_F\u0102R\u0102_COAJ\u0102_2\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_2.jpg 1000w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_2-300x300.jpg 300w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_2-150x150.jpg 150w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_2-768x768.jpg 768w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_2-550x550.jpg 550w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_2-600x600.jpg 600w, https:\/\/lefrucom.com\/wp-content\/uploads\/2016\/12\/21.-MERE_USCATE_RONDELE_FARA_COAJA_2-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"eltdf-ig-image\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"image\" class=\"eltdf-ig-lightbox\" href=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/MERE_USCATE_RONDELE_FARA_COAJA.jpg\" data-rel=\"prettyPhoto[image_gallery_pretty_photo-922]\" title=\"MERE_USCATE_RONDELE_F\u0102R\u0102_COAJ\u0102\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/MERE_USCATE_RONDELE_FARA_COAJA.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/MERE_USCATE_RONDELE_FARA_COAJA.jpg 1000w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/MERE_USCATE_RONDELE_FARA_COAJA-300x300.jpg 300w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/MERE_USCATE_RONDELE_FARA_COAJA-150x150.jpg 150w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/MERE_USCATE_RONDELE_FARA_COAJA-768x768.jpg 768w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/MERE_USCATE_RONDELE_FARA_COAJA-550x550.jpg 550w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/MERE_USCATE_RONDELE_FARA_COAJA-600x600.jpg 600w, https:\/\/lefrucom.com\/wp-content\/uploads\/2023\/06\/MERE_USCATE_RONDELE_FARA_COAJA-100x100.jpg 100w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column offset=&#8221;vc_hidden-lg vc_hidden-md&#8221; css=&#8221;.vc_custom_1685731914096{padding-right: 8% !important;padding-left: 8% !important;}&#8221;][vc_column_text] [\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1684664857254{margin-top: -50px !important;padding-top: 100px !important;}&#8221; simple_background_color=&#8221;#f9f9f9&#8243;][vc_column width=&#8221;1\/2&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1685820357185{padding-bottom: 110px !important;}&#8221;][vc_column offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][vc_single_image image=&#8221;14955&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1685868175763{margin-top: -45% !important;padding-right: 20% !important;padding-bottom: 120px !important;padding-left: 20% !important;}&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1685820337693{margin-top: -100px !important;margin-bottom: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-13828","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lefrucom.com\/ro\/wp-json\/wp\/v2\/pages\/13828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lefrucom.com\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lefrucom.com\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lefrucom.com\/ro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lefrucom.com\/ro\/wp-json\/wp\/v2\/comments?post=13828"}],"version-history":[{"count":41,"href":"https:\/\/lefrucom.com\/ro\/wp-json\/wp\/v2\/pages\/13828\/revisions"}],"predecessor-version":[{"id":15139,"href":"https:\/\/lefrucom.com\/ro\/wp-json\/wp\/v2\/pages\/13828\/revisions\/15139"}],"wp:attachment":[{"href":"https:\/\/lefrucom.com\/ro\/wp-json\/wp\/v2\/media?parent=13828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}